{"id":19689,"date":"2015-05-18T11:18:07","date_gmt":"2015-05-18T09:18:07","guid":{"rendered":"https:\/\/www.brazzale.com\/project\/provolone-fiaschettino-fiaschetto-e-boccione-zogi\/"},"modified":"2020-08-26T13:19:49","modified_gmt":"2020-08-26T11:19:49","slug":"provolone-fiaschettino-fiaschetto-e-boccione-zogi","status":"publish","type":"dt_portfolio","link":"https:\/\/www.brazzale.com\/en\/project\/provolone-fiaschettino-fiaschetto-e-boccione-zogi\/","title":{"rendered":"Provolone Fiaschettino, Fiaschetto e Boccione"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column width=&#8221;3\/4&#8243;][vc_column_text]<\/p>\n<h2>Provolone Fiaschettino, Fiaschetto e Boccione &#8211; Zogi<\/h2>\n<p>[\/vc_column_text]<div class=\"ult-spacer spacer-6a04f5d5428e1\" data-id=\"6a04f5d5428e1\" data-height=\"40\" data-height-mobile=\"25\" data-height-tab=\"30\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>[\/vc_column][vc_column width=&#8221;1\/4&#8243;]<a href=\"https:\/\/www.brazzale.com\/wp-content\/uploads\/2015\/07\/brazzale-prodotti-zogi-schede-fiaschettone_fiaschetto-boccione.pdf\" class=\"btn-shortcode dt-btn-m dt-btn default-btn-color default-btn-hover-color default-btn-bg-color default-btn-bg-hover-color fadeIn animate-element animation-builder\" target=\"_blank\" id=\"dt-btn-1\" rel=\"noopener\"><i class=\"fa fa-file-pdf-o\"><\/i><span>Scarica Scheda PDF<\/span><\/a><div class=\"ult-spacer spacer-6a04f5d5429aa\" data-id=\"6a04f5d5429aa\" data-height=\"40\" data-height-mobile=\"25\" data-height-tab=\"30\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;]<style type=\"text\/css\" data-type=\"the7_shortcodes-inline-css\">.shortcode-single-image-wrap.shortcode-single-image-4110a2a0f966d4199e5b3f608cb5de6a.enable-bg-rollover .rollover i,\n.shortcode-single-image-wrap.shortcode-single-image-4110a2a0f966d4199e5b3f608cb5de6a.enable-bg-rollover .rollover-video i {\n  background: ;\n  background: -webkit-linear-gradient();\n  background: linear-gradient();\n}\n.shortcode-single-image-wrap.shortcode-single-image-4110a2a0f966d4199e5b3f608cb5de6a .rollover-icon {\n  font-size: 32px;\n  color: #ffffff;\n  min-width: 44px;\n  min-height: 44px;\n  line-height: 44px;\n  border-radius: 100px;\n  border-style: solid;\n  border-width: 0px;\n}\n.dt-icon-bg-on.shortcode-single-image-wrap.shortcode-single-image-4110a2a0f966d4199e5b3f608cb5de6a .rollover-icon {\n  background: rgba(255,255,255,0.3);\n  box-shadow: none;\n}<\/style><div class=\"shortcode-single-image-wrap shortcode-single-image-4110a2a0f966d4199e5b3f608cb5de6a alignnone  enable-bg-rollover dt-icon-bg-off\" style=\"margin-top:0px; margin-bottom:0px; margin-left:0px; margin-right:0px; width:500px;\"><div class=\"shortcode-single-image\"><div class=\"fancy-media-wrap\" style=\"\"><a class=\"layzr-bg rollover rollover-zoom dt-pswp-item pswp-image\" href=\"https:\/\/www.brazzale.com\/wp-content\/uploads\/2015\/05\/prodotti-brazzale-zogi-fiaschetto_boccione.jpg\" title=\"Zogi &#8211; Provolone Fiaschettino, Fiaschetto e Boccione\" data-dt-img-description=\"\" data-large_image_width=\"1000\" data-large_image_height = \"700\"  style=\"\"><img fetchpriority=\"high\" decoding=\"async\" class=\"preload-me lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20500%20350&#39;%2F%3E\" data-src=\"https:\/\/www.brazzale.com\/wp-content\/uploads\/2015\/05\/prodotti-brazzale-zogi-fiaschetto_boccione-500x350.jpg\" data-srcset=\"https:\/\/www.brazzale.com\/wp-content\/uploads\/2015\/05\/prodotti-brazzale-zogi-fiaschetto_boccione-500x350.jpg 500w, https:\/\/www.brazzale.com\/wp-content\/uploads\/2015\/05\/prodotti-brazzale-zogi-fiaschetto_boccione.jpg 1000w\" loading=\"eager\" style=\"--ratio: 500 \/ 350\" sizes=\"(max-width: 500px) 100vw, 500px\" width=\"500\" height=\"350\"  data-dt-location=\"https:\/\/www.brazzale.com\/en\/project\/provolone-fiaschettino-fiaschetto-e-boccione-zogi\/prodotti-brazzale-zogi-fiaschetto_boccione\/\" alt=\"Zogi - Provolone Fiaschettino, Fiaschetto e Boccione\" \/><\/a><\/div><\/div><\/div><div class=\"ult-spacer spacer-6a04f5d543be8\" data-id=\"6a04f5d543be8\" data-height=\"30\" data-height-mobile=\"25\" data-height-tab=\"25\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>[\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">Il fiaschetto \u00e8 caratterizzato da un gusto gradevolmente piccante. La pasta, di colore paglierino chiaro, presenta la caratteristica sfogliatura. Viene proposto a crosta naturale, in varie grammature, a peso variabile. Se richiesto viene affumicato.<\/p>\n<p>[\/vc_column_text]<div class=\"ult-spacer spacer-6a04f5d543c02\" data-id=\"6a04f5d543c02\" data-height=\"25\" data-height-mobile=\"20\" data-height-tab=\"20\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div><div class=\"hr-thin style-line\" style=\"width: 100%;border-top-width: 1px;\"><\/div><div class=\"ult-spacer spacer-6a04f5d543c56\" data-id=\"6a04f5d543c56\" data-height=\"25\" data-height-mobile=\"20\" data-height-tab=\"20\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>[vc_column_text]<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti:<\/strong> <strong>Latte<\/strong>, sale, caglio, senza conservanti.<\/p>\n<p>[\/vc_column_text]<div class=\"ult-spacer spacer-6a04f5d543c69\" data-id=\"6a04f5d543c69\" data-height=\"30\" data-height-mobile=\"25\" data-height-tab=\"25\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>[vc_column_text]<\/p>\n<h4 style=\"text-align: justify;\">DICHIARAZIONE NUTRIZIONALE<\/h4>\n<p style=\"text-align: justify;\">[\/vc_column_text]<div class=\"ult-spacer spacer-6a04f5d543c82\" data-id=\"6a04f5d543c82\" data-height=\"20\" data-height-mobile=\"15\" data-height-tab=\"15\" data-height-tab-portrait=\"20\" data-height-mobile-landscape=\"10\" style=\"clear:both;display:block;\"><\/div>[vc_table vc_table_theme=&#8221;classic_blue&#8221; allow_html=&#8221;1&#8243;]<\/p>\n<p>Valori%20medi%20per%20100%20g,|Energia,1495%20kJ%20%3C%2Fbr%3E%20%0A360%20kcal|Grassi%20%3C%2Fbr%3E%20%0Adi%20cui%3A%20acidi%20grassi%20saturi,29%20g%20%3C%2Fbr%3E%20%0A20%20g|Carboidrati%20%3C%2Fbr%3E%20%0Adi%20cui%3A%20zuccheri,0%2C8%20g%20%3C%2Fbr%3E%20%0A0%20g|Proteine,24%20g|Sale,2%20g<\/p>\n<p>[\/vc_table]<div class=\"ult-spacer spacer-6a04f5d543c99\" data-id=\"6a04f5d543c99\" data-height=\"30\" data-height-mobile=\"25\" data-height-tab=\"25\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column width=&#8221;3\/4&#8243;][vc_column_text] Provolone Fiaschettino, Fiaschetto e Boccione &#8211; Zogi [\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text] Il fiaschetto \u00e8 caratterizzato da un gusto gradevolmente piccante. La pasta, di colore paglierino chiaro, presenta la caratteristica sfogliatura. Viene proposto a crosta naturale, in varie grammature, a peso variabile. Se richiesto viene affumicato. [\/vc_column_text][vc_column_text] Ingredienti: Latte, sale, caglio, senza conservanti. [\/vc_column_text][vc_column_text]&hellip;<\/p>\n","protected":false},"author":10,"featured_media":9973,"comment_status":"closed","ping_status":"closed","template":"","dt_portfolio_category":[356,349,367,358],"dt_portfolio_tags":[],"class_list":["post-19689","dt_portfolio","type-dt_portfolio","status-publish","has-post-thumbnail","hentry","dt_portfolio_category-brands","dt_portfolio_category-products","dt_portfolio_category-provolone-en","dt_portfolio_category-zogi-marchi-en","dt_portfolio_category-356","dt_portfolio_category-349","dt_portfolio_category-367","dt_portfolio_category-358","description-off"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Provolone Fiaschettino, Fiaschetto e Boccione - Brazzale S.p.A.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.brazzale.com\/en\/project\/provolone-fiaschettino-fiaschetto-e-boccione-zogi\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Provolone Fiaschettino, Fiaschetto e Boccione - Brazzale S.p.A.\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column width=&#8221;3\/4&#8243;][vc_column_text] Provolone Fiaschettino, Fiaschetto e Boccione &#8211; Zogi [\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text] Il fiaschetto \u00e8 caratterizzato da un gusto gradevolmente piccante. La pasta, di colore paglierino chiaro, presenta la caratteristica sfogliatura. Viene proposto a crosta naturale, in varie grammature, a peso variabile. Se richiesto viene affumicato. [\/vc_column_text][vc_column_text] Ingredienti: Latte, sale, caglio, senza conservanti. [\/vc_column_text][vc_column_text]&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.brazzale.com\/en\/project\/provolone-fiaschettino-fiaschetto-e-boccione-zogi\/\" \/>\n<meta property=\"og:site_name\" content=\"Brazzale S.p.A.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Brazzale-spa-842517469116278\/\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-26T11:19:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.brazzale.com\/wp-content\/uploads\/2015\/05\/prodotti-brazzale-zogi-fiaschetto_boccione.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.brazzale.com\\\/en\\\/project\\\/provolone-fiaschettino-fiaschetto-e-boccione-zogi\\\/\",\"url\":\"https:\\\/\\\/www.brazzale.com\\\/en\\\/project\\\/provolone-fiaschettino-fiaschetto-e-boccione-zogi\\\/\",\"name\":\"Provolone Fiaschettino, Fiaschetto e Boccione - Brazzale S.p.A.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.brazzale.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.brazzale.com\\\/en\\\/project\\\/provolone-fiaschettino-fiaschetto-e-boccione-zogi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.brazzale.com\\\/en\\\/project\\\/provolone-fiaschettino-fiaschetto-e-boccione-zogi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.brazzale.com\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/prodotti-brazzale-zogi-fiaschetto_boccione.jpg\",\"datePublished\":\"2015-05-18T09:18:07+00:00\",\"dateModified\":\"2020-08-26T11:19:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.brazzale.com\\\/en\\\/project\\\/provolone-fiaschettino-fiaschetto-e-boccione-zogi\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.brazzale.com\\\/en\\\/project\\\/provolone-fiaschettino-fiaschetto-e-boccione-zogi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.brazzale.com\\\/en\\\/project\\\/provolone-fiaschettino-fiaschetto-e-boccione-zogi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.brazzale.com\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/prodotti-brazzale-zogi-fiaschetto_boccione.jpg\",\"contentUrl\":\"https:\\\/\\\/www.brazzale.com\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/prodotti-brazzale-zogi-fiaschetto_boccione.jpg\",\"width\":1000,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.brazzale.com\\\/en\\\/project\\\/provolone-fiaschettino-fiaschetto-e-boccione-zogi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portafoglio\",\"item\":\"https:\\\/\\\/www.brazzale.com\\\/project\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Provolone Fiaschettino, Fiaschetto e Boccione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.brazzale.com\\\/#website\",\"url\":\"https:\\\/\\\/www.brazzale.com\\\/\",\"name\":\"Brazzale S.p.A.\",\"description\":\"Brazzale S.p.A. dal 1784\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.brazzale.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.brazzale.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.brazzale.com\\\/#organization\",\"name\":\"Brazzale S.p.A.\",\"url\":\"https:\\\/\\\/www.brazzale.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.brazzale.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.brazzale.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/brazzale-logo-2023-seo.png\",\"contentUrl\":\"https:\\\/\\\/www.brazzale.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/brazzale-logo-2023-seo.png\",\"width\":600,\"height\":378,\"caption\":\"Brazzale S.p.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.brazzale.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Brazzale-spa-842517469116278\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Provolone Fiaschettino, Fiaschetto e Boccione - Brazzale S.p.A.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.brazzale.com\/en\/project\/provolone-fiaschettino-fiaschetto-e-boccione-zogi\/","og_locale":"en_US","og_type":"article","og_title":"Provolone Fiaschettino, Fiaschetto e Boccione - Brazzale S.p.A.","og_description":"[vc_row][vc_column width=&#8221;3\/4&#8243;][vc_column_text] Provolone Fiaschettino, Fiaschetto e Boccione &#8211; Zogi [\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text] Il fiaschetto \u00e8 caratterizzato da un gusto gradevolmente piccante. La pasta, di colore paglierino chiaro, presenta la caratteristica sfogliatura. Viene proposto a crosta naturale, in varie grammature, a peso variabile. Se richiesto viene affumicato. [\/vc_column_text][vc_column_text] Ingredienti: Latte, sale, caglio, senza conservanti. [\/vc_column_text][vc_column_text]&hellip;","og_url":"https:\/\/www.brazzale.com\/en\/project\/provolone-fiaschettino-fiaschetto-e-boccione-zogi\/","og_site_name":"Brazzale S.p.A.","article_publisher":"https:\/\/www.facebook.com\/Brazzale-spa-842517469116278\/","article_modified_time":"2020-08-26T11:19:49+00:00","og_image":[{"width":1000,"height":700,"url":"https:\/\/www.brazzale.com\/wp-content\/uploads\/2015\/05\/prodotti-brazzale-zogi-fiaschetto_boccione.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.brazzale.com\/en\/project\/provolone-fiaschettino-fiaschetto-e-boccione-zogi\/","url":"https:\/\/www.brazzale.com\/en\/project\/provolone-fiaschettino-fiaschetto-e-boccione-zogi\/","name":"Provolone Fiaschettino, Fiaschetto e Boccione - Brazzale S.p.A.","isPartOf":{"@id":"https:\/\/www.brazzale.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.brazzale.com\/en\/project\/provolone-fiaschettino-fiaschetto-e-boccione-zogi\/#primaryimage"},"image":{"@id":"https:\/\/www.brazzale.com\/en\/project\/provolone-fiaschettino-fiaschetto-e-boccione-zogi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.brazzale.com\/wp-content\/uploads\/2015\/05\/prodotti-brazzale-zogi-fiaschetto_boccione.jpg","datePublished":"2015-05-18T09:18:07+00:00","dateModified":"2020-08-26T11:19:49+00:00","breadcrumb":{"@id":"https:\/\/www.brazzale.com\/en\/project\/provolone-fiaschettino-fiaschetto-e-boccione-zogi\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.brazzale.com\/en\/project\/provolone-fiaschettino-fiaschetto-e-boccione-zogi\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.brazzale.com\/en\/project\/provolone-fiaschettino-fiaschetto-e-boccione-zogi\/#primaryimage","url":"https:\/\/www.brazzale.com\/wp-content\/uploads\/2015\/05\/prodotti-brazzale-zogi-fiaschetto_boccione.jpg","contentUrl":"https:\/\/www.brazzale.com\/wp-content\/uploads\/2015\/05\/prodotti-brazzale-zogi-fiaschetto_boccione.jpg","width":1000,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/www.brazzale.com\/en\/project\/provolone-fiaschettino-fiaschetto-e-boccione-zogi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portafoglio","item":"https:\/\/www.brazzale.com\/project\/"},{"@type":"ListItem","position":2,"name":"Provolone Fiaschettino, Fiaschetto e Boccione"}]},{"@type":"WebSite","@id":"https:\/\/www.brazzale.com\/#website","url":"https:\/\/www.brazzale.com\/","name":"Brazzale S.p.A.","description":"Brazzale S.p.A. dal 1784","publisher":{"@id":"https:\/\/www.brazzale.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.brazzale.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.brazzale.com\/#organization","name":"Brazzale S.p.A.","url":"https:\/\/www.brazzale.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.brazzale.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.brazzale.com\/wp-content\/uploads\/2023\/06\/brazzale-logo-2023-seo.png","contentUrl":"https:\/\/www.brazzale.com\/wp-content\/uploads\/2023\/06\/brazzale-logo-2023-seo.png","width":600,"height":378,"caption":"Brazzale S.p.A."},"image":{"@id":"https:\/\/www.brazzale.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Brazzale-spa-842517469116278\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.brazzale.com\/en\/wp-json\/wp\/v2\/dt_portfolio\/19689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brazzale.com\/en\/wp-json\/wp\/v2\/dt_portfolio"}],"about":[{"href":"https:\/\/www.brazzale.com\/en\/wp-json\/wp\/v2\/types\/dt_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.brazzale.com\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brazzale.com\/en\/wp-json\/wp\/v2\/comments?post=19689"}],"version-history":[{"count":1,"href":"https:\/\/www.brazzale.com\/en\/wp-json\/wp\/v2\/dt_portfolio\/19689\/revisions"}],"predecessor-version":[{"id":22546,"href":"https:\/\/www.brazzale.com\/en\/wp-json\/wp\/v2\/dt_portfolio\/19689\/revisions\/22546"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brazzale.com\/en\/wp-json\/wp\/v2\/media\/9973"}],"wp:attachment":[{"href":"https:\/\/www.brazzale.com\/en\/wp-json\/wp\/v2\/media?parent=19689"}],"wp:term":[{"taxonomy":"dt_portfolio_category","embeddable":true,"href":"https:\/\/www.brazzale.com\/en\/wp-json\/wp\/v2\/dt_portfolio_category?post=19689"},{"taxonomy":"dt_portfolio_tags","embeddable":true,"href":"https:\/\/www.brazzale.com\/en\/wp-json\/wp\/v2\/dt_portfolio_tags?post=19689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}